{"id":45,"date":"2025-06-24T16:03:01","date_gmt":"2025-06-24T14:03:01","guid":{"rendered":"http:\/\/www.albergopertosa.it\/?p=45"},"modified":"2025-07-02T09:55:25","modified_gmt":"2025-07-02T07:55:25","slug":"camera-3","status":"publish","type":"post","link":"http:\/\/www.albergopertosa.it\/index.php\/2025\/06\/24\/camera-3\/","title":{"rendered":"Le nostre camere"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9c026&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9c026\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"588\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano-1024x588.jpg\" alt=\"\" class=\"wp-image-20\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano-1024x588.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano-300x172.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano-768x441.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano-1536x883.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1208-Pano.jpg 1928w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9c932&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9c932\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"27\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano-1024x676.jpg\" alt=\"\" class=\"wp-image-27\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano-1024x676.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano-300x198.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano-768x507.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano-1536x1015.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1261-Pano.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9d12a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9d12a\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"773\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"189\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-1024x773.jpg\" alt=\"\" class=\"wp-image-189\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-1024x773.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-300x227.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-768x580.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-1536x1160.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1-390x293.jpg 390w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1235-Pano-copia-1.jpg 1915w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9d91b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9d91b\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"24\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224-1024x682.jpg\" alt=\"\" class=\"wp-image-24\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224-1024x682.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224-300x200.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224-768x512.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224-1536x1024.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1224.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9e157&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9e157\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"22\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219-1024x682.jpg\" alt=\"\" class=\"wp-image-22\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219-1024x682.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219-300x200.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219-768x512.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219-1536x1024.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/IMG_1219.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9e915&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9e915\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"172\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-1024x683.jpg\" alt=\"\" class=\"wp-image-172\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-1024x683.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-300x200.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-768x512.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-1536x1024.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1520-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9f0d9&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9f0d9\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"13\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/camera1-1024x683.jpeg\" alt=\"\" class=\"wp-image-13\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/camera1-1024x683.jpeg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/camera1-300x200.jpeg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/camera1-768x512.jpeg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/camera1.jpeg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65d9f8a7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65d9f8a7\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"166\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-1024x683.jpg\" alt=\"\" class=\"wp-image-166\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-1024x683.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-300x200.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-768x512.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-1536x1024.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1506-Pano-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04c65da0039&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04c65da0039\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"165\" src=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-1024x683.jpg\" alt=\"\" class=\"wp-image-165\" srcset=\"http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-1024x683.jpg 1024w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-300x200.jpg 300w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-768x512.jpg 768w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-1536x1024.jpg 1536w, http:\/\/www.albergopertosa.it\/wp-content\/uploads\/2025\/06\/I62A1500-Pano-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":20,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-45","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camere"],"_links":{"self":[{"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/posts\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":7,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"predecessor-version":[{"id":192,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/posts\/45\/revisions\/192"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/media\/20"}],"wp:attachment":[{"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.albergopertosa.it\/index.php\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}